{"id":29480,"date":"2024-06-05T21:50:05","date_gmt":"2024-06-05T19:50:05","guid":{"rendered":"https:\/\/vintagecycling.store\/?post_type=product&#038;p=29480"},"modified":"2026-05-13T15:36:47","modified_gmt":"2026-05-13T13:36:47","slug":"ranking-general-5","status":"publish","type":"product","link":"https:\/\/vintagecycling.store\/es\/retro-wielershirt\/rolini-1995\/","title":{"rendered":"CAMISETA CICLISMO ROLINI DIAMOND 1995"},"content":{"rendered":"<p>ROLINI 1995 Patrocinador privado del ciclista de ciclocross Danny de Bie<\/p>","protected":false},"excerpt":{"rendered":"<p>ROLINI 1995 Patrocinador privado del ciclista de ciclocross Danny de Bie<\/p>","protected":false},"featured_media":29490,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-29480","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ROLINI-DIAMANT  1995    WIELERSHIRT - Vintage Cycling Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ROLINI-DIAMANT  1995    WIELERSHIRT - Vintage Cycling Store\" \/>\n<meta property=\"og:description\" content=\"ROLINI 1995\u00a0 Privesponsor van Veldrijder Danny de Bie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/\" \/>\n<meta property=\"og:site_name\" content=\"Vintage Cycling Store\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:36:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1899-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/classement-general-33\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/classement-general-33\\\/\",\"name\":\"ROLINI-DIAMANT 1995 WIELERSHIRT - Vintage Cycling Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/classement-general-33\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/classement-general-33\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_1899-scaled.jpg\",\"datePublished\":\"2024-06-05T19:50:05+00:00\",\"dateModified\":\"2026-05-13T13:36:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/classement-general-33\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/classement-general-33\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/classement-general-33\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_1899-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_1899-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"ROLINI 1995\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/maillot-de-cyclisme-retro\\\/classement-general-33\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ROLINI-DIAMANT 1995 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Vintage Cycling Store\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Vintage Cycling Store\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Vintage Cycling Store\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAMISETA DE CICLISMO ROLINI DIAMOND 1995 - Tienda de Ciclismo Vintage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/","og_locale":"es_ES","og_type":"article","og_title":"ROLINI-DIAMANT  1995    WIELERSHIRT - Vintage Cycling Store","og_description":"ROLINI 1995\u00a0 Privesponsor van Veldrijder Danny de Bie","og_url":"https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/","og_site_name":"Vintage Cycling Store","article_modified_time":"2026-05-13T13:36:47+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1899-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/","url":"https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/","name":"CAMISETA DE CICLISMO ROLINI DIAMOND 1995 - Tienda de Ciclismo Vintage","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/#primaryimage"},"thumbnailUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2024\/06\/IMG_1899-scaled.jpg","datePublished":"2024-06-05T19:50:05+00:00","dateModified":"2026-05-13T13:36:47+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/#primaryimage","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2024\/06\/IMG_1899-scaled.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2024\/06\/IMG_1899-scaled.jpg","width":1920,"height":2560,"caption":"ROLINI 1995"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/fr\/maillot-de-cyclisme-retro\/classement-general-33\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"ROLINI-DIAMANT 1995 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Tienda de ciclismo vintage","description":"miles de maillots ciclistas originales - \u00a1pide tu r\u00e9plica!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Tienda de ciclismo vintage","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Vintage Cycling Store"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product\/29480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/media\/29490"}],"wp:attachment":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/media?parent=29480"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product_brand?post=29480"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product_cat?post=29480"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product_tag?post=29480"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}