{"id":3731,"date":"2023-01-24T18:06:07","date_gmt":"2023-01-24T18:06:07","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/kela-tapijt-jack\/"},"modified":"2026-06-07T17:54:58","modified_gmt":"2026-06-07T15:54:58","slug":"chaqueta-de-alfombra-kela","status":"publish","type":"product","link":"https:\/\/vintagecycling.store\/es\/retro-wielershirt\/kela-tapijt-jack\/","title":{"rendered":"CHAQUETA DE CICLISMO KELA (b) CARPET 1973"},"content":{"rendered":"<p>ALFOMBRA KELA 1973<\/p>\n<p>\u00bfC\u00f3mo diablos se consigue una camisa\/chaqueta as\u00ed?<\/p>\n<p>A veces simplemente a trav\u00e9s de ciclistas, otras de coleccionistas y, a veces, simplemente por pura coincidencia.<\/p>\n<p>En este caso fue pura casualidad!!!!!!!!!<\/p>\n<p>Hice un paseo en bicicleta de 250 km por Veluwe (de Apeldoorn a Apeldoorn) y casi al final del recorrido pas\u00e9 por una f\u00e1brica de KELA TAPIJT. Nombre familiar, pens\u00e9, equipo ciclista ?????<\/p>\n<p>Al llegar a casa consult\u00e9 unos anuarios ciclistas y, s\u00ed, \u2026\u2026\u2026\u2026\u2026\u2026.. un equipo ciclista del a\u00f1o 1973.<\/p>\n<p>Entonces envi\u00e9 una nota a la f\u00e1brica, a trav\u00e9s de ellos entr\u00e9 en contacto con el ex l\u00edder del equipo y \u00e9l me recomend\u00f3 a Peter van Stralen de Hippolytushoef.<\/p>\n<p>Al final pudo ayudarme con estas camisetas, as\u00ed que volv\u00ed a dar un paseo en bicicleta.<\/p>","protected":false},"excerpt":{"rendered":"<p>KELA TAPIJT\u00a0 1973 Hoe kom je in hemelsnaam aan zon shirt\/jack ???? Soms gewoon via renners, andere verzamelaars en soms gewoon puur toeval. In dit geval was het puur toeval !!!!!!!!!! Ik maakte een fietstochtje van 250 km over de Veluwe (van Apeldoorn naar Apeldoorn) en bijna op het einde van de rit kwam ik [&hellip;]<\/p>\n","protected":false},"featured_media":188271,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-3731","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KELA (b) TAPIJT   1973   WIELERJACK - Vintage Cycling Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KELA (b) TAPIJT   1973   WIELERJACK - Vintage Cycling Store\" \/>\n<meta property=\"og:description\" content=\"KELA TAPIJT\u00a0 1973 Hoe kom je in hemelsnaam aan zon shirt\/jack ???? Soms gewoon via renners, andere verzamelaars en soms gewoon puur toeval. In dit geval was het puur toeval !!!!!!!!!! Ik maakte een fietstochtje van 250 km over de Veluwe (van Apeldoorn naar Apeldoorn) en bijna op het einde van de rit kwam ik [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/\" \/>\n<meta property=\"og:site_name\" content=\"Vintage Cycling Store\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-07T15:54:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/003-8-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/fr\\\/retro-wielershirt\\\/kela-tapijt-jack\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/fr\\\/retro-wielershirt\\\/kela-tapijt-jack\\\/\",\"name\":\"KELA (b) TAPIJT 1973 WIELERJACK - Vintage Cycling Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/fr\\\/retro-wielershirt\\\/kela-tapijt-jack\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/fr\\\/retro-wielershirt\\\/kela-tapijt-jack\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/003-8-scaled.jpg\",\"datePublished\":\"2023-01-24T18:06:07+00:00\",\"dateModified\":\"2026-06-07T15:54:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/fr\\\/retro-wielershirt\\\/kela-tapijt-jack\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/fr\\\/retro-wielershirt\\\/kela-tapijt-jack\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/fr\\\/retro-wielershirt\\\/kela-tapijt-jack\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/003-8-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/003-8-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"KELA TAPIJT\u00a0 1973\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/fr\\\/retro-wielershirt\\\/kela-tapijt-jack\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KELA (b) TAPIJT 1973 WIELERJACK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Vintage Cycling Store\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Vintage Cycling Store\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Vintage Cycling Store\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHAQUETA DE CICLISMO KELA (b) CARPET 1973 - Tienda de ciclismo vintage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/","og_locale":"es_ES","og_type":"article","og_title":"KELA (b) TAPIJT   1973   WIELERJACK - Vintage Cycling Store","og_description":"KELA TAPIJT\u00a0 1973 Hoe kom je in hemelsnaam aan zon shirt\/jack ???? Soms gewoon via renners, andere verzamelaars en soms gewoon puur toeval. In dit geval was het puur toeval !!!!!!!!!! Ik maakte een fietstochtje van 250 km over de Veluwe (van Apeldoorn naar Apeldoorn) en bijna op het einde van de rit kwam ik [&hellip;]","og_url":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/","og_site_name":"Vintage Cycling Store","article_modified_time":"2026-06-07T15:54:58+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/003-8-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/","name":"CHAQUETA DE CICLISMO KELA (b) CARPET 1973 - Tienda de ciclismo vintage","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/#primaryimage"},"image":{"@id":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/#primaryimage"},"thumbnailUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/003-8-scaled.jpg","datePublished":"2023-01-24T18:06:07+00:00","dateModified":"2026-06-07T15:54:58+00:00","breadcrumb":{"@id":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/#primaryimage","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/003-8-scaled.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/003-8-scaled.jpg","width":1920,"height":2560,"caption":"KELA TAPIJT\u00a0 1973"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/kela-tapijt-jack\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"KELA (b) TAPIJT 1973 WIELERJACK"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Tienda de ciclismo vintage","description":"miles de maillots ciclistas originales - \u00a1pide tu r\u00e9plica!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Tienda de ciclismo vintage","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Vintage Cycling Store"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product\/3731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/media\/188271"}],"wp:attachment":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/media?parent=3731"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product_brand?post=3731"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product_cat?post=3731"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product_tag?post=3731"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}