{"id":5182,"date":"2023-01-24T18:24:28","date_gmt":"2023-01-24T18:24:28","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/cilo-aufina\/"},"modified":"2026-05-13T15:37:00","modified_gmt":"2026-05-13T13:37:00","slug":"cilo-aufina","status":"publish","type":"product","link":"https:\/\/vintagecycling.store\/es\/retro-wielershirt\/cilo-aufina\/","title":{"rendered":"CAMISETA CICLISMO CILO-AUFINA (a) 1982"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":5181,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-5182","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CILO-AUFINA (a) 1982 WIELERSHIRT - Vintage Cycling Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CILO-AUFINA (a) 1982 WIELERSHIRT - Vintage Cycling Store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/\" \/>\n<meta property=\"og:site_name\" content=\"Vintage Cycling Store\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:37:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/SSA43912.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/retro-wielershirt\\\/cilo-aufina\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/retro-wielershirt\\\/cilo-aufina\\\/\",\"name\":\"CILO-AUFINA (a) 1982 WIELERSHIRT - Vintage Cycling Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/retro-wielershirt\\\/cilo-aufina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/retro-wielershirt\\\/cilo-aufina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43912.jpg\",\"datePublished\":\"2023-01-24T18:24:28+00:00\",\"dateModified\":\"2026-05-13T13:37:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/retro-wielershirt\\\/cilo-aufina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/retro-wielershirt\\\/cilo-aufina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/retro-wielershirt\\\/cilo-aufina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43912.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43912.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/fr\\\/retro-wielershirt\\\/cilo-aufina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CILO-AUFINA (a) 1982 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Vintage Cycling Store\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Vintage Cycling Store\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Vintage Cycling Store\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAMISETA CICLISMO CILO-AUFINA (a) 1982 - Tienda de ciclismo vintage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/","og_locale":"es_ES","og_type":"article","og_title":"CILO-AUFINA (a) 1982 WIELERSHIRT - Vintage Cycling Store","og_url":"https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/","og_site_name":"Vintage Cycling Store","article_modified_time":"2026-05-13T13:37:00+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/SSA43912.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/","url":"https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/","name":"CAMISETA CICLISMO CILO-AUFINA (a) 1982 - Tienda de ciclismo vintage","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/#primaryimage"},"thumbnailUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/SSA43912.jpg","datePublished":"2023-01-24T18:24:28+00:00","dateModified":"2026-05-13T13:37:00+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/#primaryimage","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/SSA43912.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/SSA43912.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/fr\/retro-wielershirt\/cilo-aufina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"CILO-AUFINA (a) 1982 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Tienda de ciclismo vintage","description":"miles de maillots ciclistas originales - \u00a1pide tu r\u00e9plica!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Tienda de ciclismo vintage","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Vintage Cycling Store"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product\/5182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/media\/5181"}],"wp:attachment":[{"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/media?parent=5182"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product_brand?post=5182"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product_cat?post=5182"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vintagecycling.store\/es\/wp-json\/wp\/v2\/product_tag?post=5182"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}