{"id":3841,"date":"2023-01-24T18:07:31","date_gmt":"2023-01-24T18:07:31","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/monkeytown-a-bloc\/"},"modified":"2026-06-05T15:34:28","modified_gmt":"2026-06-05T13:34:28","slug":"monkeytown-a-un-pate-de-maisons","status":"publish","type":"product","link":"https:\/\/vintagecycling.store\/fr\/retro-wielershirt\/monkeytown-a-bloc\/","title":{"rendered":"MONKEY TOWN (c)-A MAILLOT DE CYCLISME BLOC-RIDER DOMBERLANDS-FORTE 2019"},"content":{"rendered":"<p>MONKEY TOWN - UN BLOC - RUITER ROOF DORMS - FORTE 2019<\/p>","protected":false},"excerpt":{"rendered":"<p>MONKEY TOWN - UN BLOC - RUITER ROOF DORMS - FORTE 2019<\/p>","protected":false},"featured_media":188049,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-3841","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MONKEY TOWN (c)-A BLOC-RUITER DAKKAPELLEN-FORTE  2019   WIELERSHIRT - Vintage Cycling Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MONKEY TOWN (c)-A BLOC-RUITER DAKKAPELLEN-FORTE  2019   WIELERSHIRT - Vintage Cycling Store\" \/>\n<meta property=\"og:description\" content=\"MONKEY TOWN-A BLOC-RUITER DAKKAPELLEN-FORTE 2019\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/\" \/>\n<meta property=\"og:site_name\" content=\"Vintage Cycling Store\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-05T13:34:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/016-5-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/es\\\/retro-wielershirt\\\/monkeytown-a-bloc\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/es\\\/retro-wielershirt\\\/monkeytown-a-bloc\\\/\",\"name\":\"MONKEY TOWN (c)-A BLOC-RUITER DAKKAPELLEN-FORTE 2019 WIELERSHIRT - Vintage Cycling Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/es\\\/retro-wielershirt\\\/monkeytown-a-bloc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/es\\\/retro-wielershirt\\\/monkeytown-a-bloc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/016-5-scaled.jpg\",\"datePublished\":\"2023-01-24T18:07:31+00:00\",\"dateModified\":\"2026-06-05T13:34:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/es\\\/retro-wielershirt\\\/monkeytown-a-bloc\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/es\\\/retro-wielershirt\\\/monkeytown-a-bloc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/es\\\/retro-wielershirt\\\/monkeytown-a-bloc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/016-5-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/016-5-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"MONKEY TOWN (c)-A BLOC-RUITER DAKKAPELLEN-FORTE 2019\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/es\\\/retro-wielershirt\\\/monkeytown-a-bloc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MONKEY TOWN (c)-A BLOC-RUITER DAKKAPELLEN-FORTE 2019 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Vintage Cycling Store\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Vintage Cycling Store\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Vintage Cycling Store\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MONKEY TOWN (c)-A BLOC-RIDER DORMER CHAPS-FORTE 2019 CHEMISE DE CYCLISME - Vintage Cycling Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/","og_locale":"fr_FR","og_type":"article","og_title":"MONKEY TOWN (c)-A BLOC-RUITER DAKKAPELLEN-FORTE  2019   WIELERSHIRT - Vintage Cycling Store","og_description":"MONKEY TOWN-A BLOC-RUITER DAKKAPELLEN-FORTE 2019","og_url":"https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/","og_site_name":"Vintage Cycling Store","article_modified_time":"2026-06-05T13:34:28+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/016-5-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/","name":"MONKEY TOWN (c)-A BLOC-RIDER DORMER CHAPS-FORTE 2019 CHEMISE DE CYCLISME - Vintage Cycling Store","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/#primaryimage"},"image":{"@id":"https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/#primaryimage"},"thumbnailUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/016-5-scaled.jpg","datePublished":"2023-01-24T18:07:31+00:00","dateModified":"2026-06-05T13:34:28+00:00","breadcrumb":{"@id":"https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/#primaryimage","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/016-5-scaled.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/016-5-scaled.jpg","width":1920,"height":2560,"caption":"MONKEY TOWN (c)-A BLOC-RUITER DAKKAPELLEN-FORTE 2019"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cyclingjerseys-originals.com\/es\/retro-wielershirt\/monkeytown-a-bloc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"MONKEY TOWN (c)-A BLOC-RUITER DAKKAPELLEN-FORTE 2019 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Magasin de cyclisme vintage","description":"des milliers de maillots de cyclisme originaux - commandez votre r\u00e9plique !","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Magasin de cyclisme vintage","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Vintage Cycling Store"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vintagecycling.store\/fr\/wp-json\/wp\/v2\/product\/3841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vintagecycling.store\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vintagecycling.store\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vintagecycling.store\/fr\/wp-json\/wp\/v2\/media\/188049"}],"wp:attachment":[{"href":"https:\/\/vintagecycling.store\/fr\/wp-json\/wp\/v2\/media?parent=3841"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vintagecycling.store\/fr\/wp-json\/wp\/v2\/product_brand?post=3841"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vintagecycling.store\/fr\/wp-json\/wp\/v2\/product_cat?post=3841"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vintagecycling.store\/fr\/wp-json\/wp\/v2\/product_tag?post=3841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}