{"id":975,"date":"2023-01-24T17:33:30","date_gmt":"2023-01-24T17:33:30","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/cedico-2\/"},"modified":"2026-05-13T15:39:55","modified_gmt":"2026-05-13T13:39:55","slug":"cedico-2","status":"publish","type":"product","link":"https:\/\/vintagecycling.store\/it\/retro-wielershirt\/cedico-2\/","title":{"rendered":"MAGLIA CICLISMO CEDICO (b)-RIGIDA 1996"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":974,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-975","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CEDICO (b)-RIGIDA  1996                                     WIELERSHIRT - Vintage Cycling Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CEDICO (b)-RIGIDA  1996                                     WIELERSHIRT - Vintage Cycling Store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Vintage Cycling Store\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:39:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ton.connectingminds.net\/wp-content\/uploads\/2023\/01\/SSA42885.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/pt\\\/retro-wielershirt\\\/cedico-2\\\/\",\"url\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/pt\\\/retro-wielershirt\\\/cedico-2\\\/\",\"name\":\"CEDICO (b)-RIGIDA 1996 WIELERSHIRT - Vintage Cycling Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/pt\\\/retro-wielershirt\\\/cedico-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/pt\\\/retro-wielershirt\\\/cedico-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA42885.jpg\",\"datePublished\":\"2023-01-24T17:33:30+00:00\",\"dateModified\":\"2026-05-13T13:39:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/pt\\\/retro-wielershirt\\\/cedico-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ton.connectingminds.net\\\/pt\\\/retro-wielershirt\\\/cedico-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/pt\\\/retro-wielershirt\\\/cedico-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA42885.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA42885.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/pt\\\/retro-wielershirt\\\/cedico-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CEDICO (b)-RIGIDA 1996 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Vintage Cycling Store\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Vintage Cycling Store\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Vintage Cycling Store\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAGLIA CICLISMO CEDICO (b)-RIGIDA 1996 - Negozio di ciclismo vintage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/","og_locale":"it_IT","og_type":"article","og_title":"CEDICO (b)-RIGIDA  1996                                     WIELERSHIRT - Vintage Cycling Store","og_url":"https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/","og_site_name":"Vintage Cycling Store","article_modified_time":"2026-05-13T13:39:55+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/www.ton.connectingminds.net\/wp-content\/uploads\/2023\/01\/SSA42885.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/","url":"https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/","name":"MAGLIA CICLISMO CEDICO (b)-RIGIDA 1996 - Negozio di ciclismo vintage","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/#primaryimage"},"image":{"@id":"https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/#primaryimage"},"thumbnailUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/SSA42885.jpg","datePublished":"2023-01-24T17:33:30+00:00","dateModified":"2026-05-13T13:39:55+00:00","breadcrumb":{"@id":"https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/#primaryimage","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/SSA42885.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/SSA42885.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/www.ton.connectingminds.net\/pt\/retro-wielershirt\/cedico-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"CEDICO (b)-RIGIDA 1996 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Negozio di biciclette d&#039;epoca","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Negozio di biciclette d&#039;epoca","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Vintage Cycling Store"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vintagecycling.store\/it\/wp-json\/wp\/v2\/product\/975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vintagecycling.store\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vintagecycling.store\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vintagecycling.store\/it\/wp-json\/wp\/v2\/media\/974"}],"wp:attachment":[{"href":"https:\/\/vintagecycling.store\/it\/wp-json\/wp\/v2\/media?parent=975"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vintagecycling.store\/it\/wp-json\/wp\/v2\/product_brand?post=975"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vintagecycling.store\/it\/wp-json\/wp\/v2\/product_cat?post=975"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vintagecycling.store\/it\/wp-json\/wp\/v2\/product_tag?post=975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}