{"id":3347,"date":"2023-01-24T18:01:40","date_gmt":"2023-01-24T18:01:40","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/differdange-c-jans-magic-sportsfood\/"},"modified":"2026-05-13T15:38:16","modified_gmt":"2026-05-13T13:38:16","slug":"diferenge-c-jans-comida-esportiva-magica","status":"publish","type":"product","link":"https:\/\/vintagecycling.store\/pt\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/","title":{"rendered":"CAMISA DE CICLISMO DIFFERDANGE (g)-C.JANS-LOSCH-MAGIC SPORTSFOOD 2011"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3346,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-3347","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIFFERDANGE (g)-C.JANS-LOSCH-MAGIC SPORTSFOOD  2011  WIELERSHIRT - Vintage Cycling Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIFFERDANGE (g)-C.JANS-LOSCH-MAGIC SPORTSFOOD  2011  WIELERSHIRT - Vintage Cycling Store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/\" \/>\n<meta property=\"og:site_name\" content=\"Vintage Cycling Store\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:38:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_0898-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/differdange-c-jans-magic-sportsfood\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/differdange-c-jans-magic-sportsfood\\\/\",\"name\":\"DIFFERDANGE (g)-C.JANS-LOSCH-MAGIC SPORTSFOOD 2011 WIELERSHIRT - Vintage Cycling Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/differdange-c-jans-magic-sportsfood\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/differdange-c-jans-magic-sportsfood\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_0898-scaled.jpg\",\"datePublished\":\"2023-01-24T18:01:40+00:00\",\"dateModified\":\"2026-05-13T13:38:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/differdange-c-jans-magic-sportsfood\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/differdange-c-jans-magic-sportsfood\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/differdange-c-jans-magic-sportsfood\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_0898-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_0898-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/differdange-c-jans-magic-sportsfood\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DIFFERDANGE (g)-C.JANS-LOSCH-MAGIC SPORTSFOOD 2011 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Vintage Cycling Store\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Vintage Cycling Store\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagecycling.store\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Vintage Cycling Store\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAMISA DE CICLISMO DIFFERDANGE (g)-C.JANS-LOSCH-MAGIC SPORTSFOOD 2011 - Loja de ciclismo vintage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/","og_locale":"pt_PT","og_type":"article","og_title":"DIFFERDANGE (g)-C.JANS-LOSCH-MAGIC SPORTSFOOD  2011  WIELERSHIRT - Vintage Cycling Store","og_url":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/","og_site_name":"Vintage Cycling Store","article_modified_time":"2026-05-13T13:38:16+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_0898-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/","url":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/","name":"CAMISA DE CICLISMO DIFFERDANGE (g)-C.JANS-LOSCH-MAGIC SPORTSFOOD 2011 - Loja de ciclismo vintage","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/#primaryimage"},"thumbnailUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/IMG_0898-scaled.jpg","datePublished":"2023-01-24T18:01:40+00:00","dateModified":"2026-05-13T13:38:16+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/#primaryimage","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/IMG_0898-scaled.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/IMG_0898-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/differdange-c-jans-magic-sportsfood\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"DIFFERDANGE (g)-C.JANS-LOSCH-MAGIC SPORTSFOOD 2011 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Loja de ciclismo vintage","description":"milhares de camisas de ciclismo originais - encomende a sua r\u00e9plica!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Loja de ciclismo vintage","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Vintage Cycling Store"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vintagecycling.store\/pt\/wp-json\/wp\/v2\/product\/3347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vintagecycling.store\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vintagecycling.store\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vintagecycling.store\/pt\/wp-json\/wp\/v2\/media\/3346"}],"wp:attachment":[{"href":"https:\/\/vintagecycling.store\/pt\/wp-json\/wp\/v2\/media?parent=3347"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vintagecycling.store\/pt\/wp-json\/wp\/v2\/product_brand?post=3347"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vintagecycling.store\/pt\/wp-json\/wp\/v2\/product_cat?post=3347"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vintagecycling.store\/pt\/wp-json\/wp\/v2\/product_tag?post=3347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}